{"id":42877,"date":"2025-12-18T02:44:02","date_gmt":"2025-12-18T05:44:02","guid":{"rendered":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/decisao-e-diferente-de-intencao-pastor-claudio-duarte\/"},"modified":"2025-12-18T02:44:02","modified_gmt":"2025-12-18T05:44:02","slug":"decisao-e-diferente-de-intencao-pastor-claudio-duarte","status":"publish","type":"post","link":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/decisao-e-diferente-de-intencao-pastor-claudio-duarte\/","title":{"rendered":"Decis\u00e3o \u00e9 diferente de inten\u00e7\u00e3o | Pastor Claudio Duarte"},"content":{"rendered":"<p><iframe loading=\"lazy\"  width=\"580\" height=\"385\" src=\"https:\/\/www.youtube.com\/embed\/aS9l2T9q6DM?autoplay=1\" frameborder=\"0\" allowfullscreen><\/iframe><br \/>\n<br \/>Decis\u00e3o \u00e9 diferente de inten\u00e7\u00e3o | Pastor Claudio Duarte #claudioduarte2024 #pregacao2024 #claudioduarte Agradecimento &#8230;<br \/>\n<br \/><a href=\"[https:\/\/mensagemdivina.com.br\/]\">Mensagem Divina<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decis\u00e3o \u00e9 diferente de inten\u00e7\u00e3o | Pastor Claudio Duarte #claudioduarte2024 #pregacao2024 #claudioduarte Agradecimento &#8230; Mensagem Divina<\/p>\n","protected":false},"author":1,"featured_media":42878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5955],"tags":[49902,49901,49896,49905,49899,49900,49898,49904,49895,49903,49897,1678,35580,49893,49894],"class_list":["post-42877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-claudio-duarte","tag-claudio-duarte-autoayuda","tag-claudio-duarte-crecimiento-personal","tag-claudio-duarte-desarrollo-personal","tag-claudio-duarte-desarrollo-profesional","tag-claudio-duarte-establecimiento-de-metas","tag-claudio-duarte-gestion-del-tiempo","tag-claudio-duarte-liderazgo","tag-claudio-duarte-logro-personal","tag-claudio-duarte-motivacion","tag-claudio-duarte-pensamiento-positivo","tag-claudio-duarte-superacion-personal","tag-pastor-claudio-duarte","tag-pastor-claudio-duarte-2024","tag-pastor-claudio-duarte-2025","tag-predicas-de-claudio-duarte"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/wp-json\/wp\/v2\/posts\/42877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/wp-json\/wp\/v2\/comments?post=42877"}],"version-history":[{"count":0,"href":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/wp-json\/wp\/v2\/posts\/42877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/wp-json\/wp\/v2\/media\/42878"}],"wp:attachment":[{"href":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/wp-json\/wp\/v2\/media?parent=42877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/wp-json\/wp\/v2\/categories?post=42877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mensagemdivina.com.br\/mensagemdivina\/wp-json\/wp\/v2\/tags?post=42877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}